{"id":3153,"date":"2022-06-26T01:11:40","date_gmt":"2022-06-25T18:11:40","guid":{"rendered":"https:\/\/www.napbiotec.io\/?p=3153"},"modified":"2022-06-26T01:12:18","modified_gmt":"2022-06-25T18:12:18","slug":"machine-extract-for-nap","status":"publish","type":"post","link":"https:\/\/www.napbiotec.com\/en\/machine-extract-for-nap\/","title":{"rendered":"\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e01\u0e31\u0e14\u0e2a\u0e38\u0e14\u0e25\u0e49\u0e33 \u0e17\u0e35\u0e48\u0e17\u0e33\u0e43\u0e2b\u0e49 NAP \u0e44\u0e21\u0e48\u0e40\u0e2b\u0e21\u0e37\u0e2d\u0e19\u0e43\u0e04\u0e23"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"3153\" class=\"elementor elementor-3153\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-86e5897 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"86e5897\" data-element_type=\"section\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-094d2ea\" data-id=\"094d2ea\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-33696c7 elementor-widget elementor-widget-text-editor\" data-id=\"33696c7\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.23.0 - 05-08-2024 *\/\n.elementor-widget-text-editor.elementor-drop-cap-view-stacked .elementor-drop-cap{background-color:#69727d;color:#fff}.elementor-widget-text-editor.elementor-drop-cap-view-framed .elementor-drop-cap{color:#69727d;border:3px solid;background-color:transparent}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap{margin-top:8px}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap-letter{width:1em;height:1em}.elementor-widget-text-editor .elementor-drop-cap{float:left;text-align:center;line-height:1;font-size:50px}.elementor-widget-text-editor .elementor-drop-cap-letter{display:inline-block}<\/style>\t\t\t\t<p>\u0e01\u0e32\u0e23\u0e08\u0e30\u0e21\u0e35\u0e2a\u0e32\u0e23\u0e2a\u0e01\u0e31\u0e14\u0e2a\u0e21\u0e38\u0e19\u0e44\u0e1e\u0e23\u0e17\u0e35\u0e48\u0e21\u0e35\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e \u0e01\u0e47\u0e15\u0e49\u0e2d\u0e07\u0e21\u0e35\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e01\u0e31\u0e14\u0e2a\u0e21\u0e38\u0e19\u0e44\u0e1e\u0e23\u0e17\u0e35\u0e48\u0e21\u0e35\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e40\u0e0a\u0e48\u0e19\u0e01\u0e31\u0e19 \u0e41\u0e25\u0e49\u0e27\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e01\u0e31\u0e14\u0e2a\u0e21\u0e38\u0e19\u0e44\u0e1e\u0e23\u0e02\u0e2d\u0e07 NAP \u0e08\u0e30\u0e21\u0e35\u0e2b\u0e19\u0e49\u0e32\u0e15\u0e32\u0e40\u0e1b\u0e47\u0e19\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e44\u0e23 \u0e40\u0e23\u0e32\u0e44\u0e1b\u0e14\u0e39\u0e01\u0e31\u0e19\u0e40\u0e25\u0e22<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f1b6b7e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f1b6b7e\" data-element_type=\"section\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-5d595d3\" data-id=\"5d595d3\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-990d8b5 elementor-widget elementor-widget-image\" data-id=\"990d8b5\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.23.0 - 05-08-2024 *\/\n.elementor-widget-image{text-align:center}.elementor-widget-image a{display:inline-block}.elementor-widget-image a img[src$=\".svg\"]{width:48px}.elementor-widget-image img{vertical-align:middle;display:inline-block}<\/style>\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.napbiotec.io\/wp-content\/uploads\/2022\/06\/line-2.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-title=\"line 2\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MzE1NiwidXJsIjoiaHR0cHM6XC9cL3d3dy5uYXBiaW90ZWMuY29tXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDIyXC8wNlwvbGluZS0yLmpwZyJ9\">\n\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"721\" src=\"https:\/\/www.napbiotec.com\/wp-content\/uploads\/2022\/06\/line-2-1024x923.jpg\" class=\"elementor-animation-grow attachment-large size-large wp-image-3156\" alt=\"\" srcset=\"https:\/\/www.napbiotec.com\/wp-content\/uploads\/2022\/06\/line-2-1024x923.jpg 1024w, https:\/\/www.napbiotec.com\/wp-content\/uploads\/2022\/06\/line-2-600x541.jpg 600w, https:\/\/www.napbiotec.com\/wp-content\/uploads\/2022\/06\/line-2-300x270.jpg 300w, https:\/\/www.napbiotec.com\/wp-content\/uploads\/2022\/06\/line-2-768x692.jpg 768w, https:\/\/www.napbiotec.com\/wp-content\/uploads\/2022\/06\/line-2-13x12.jpg 13w, https:\/\/www.napbiotec.com\/wp-content\/uploads\/2022\/06\/line-2.jpg 1110w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-8f34764\" data-id=\"8f34764\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9d653e5 elementor-widget elementor-widget-heading\" data-id=\"9d653e5\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.23.0 - 05-08-2024 *\/\n.elementor-heading-title{padding:0;margin:0;line-height:1}.elementor-widget-heading .elementor-heading-title[class*=elementor-size-]>a{color:inherit;font-size:inherit;line-height:inherit}.elementor-widget-heading .elementor-heading-title.elementor-size-small{font-size:15px}.elementor-widget-heading .elementor-heading-title.elementor-size-medium{font-size:19px}.elementor-widget-heading .elementor-heading-title.elementor-size-large{font-size:29px}.elementor-widget-heading .elementor-heading-title.elementor-size-xl{font-size:39px}.elementor-widget-heading .elementor-heading-title.elementor-size-xxl{font-size:59px}<\/style><h2 class=\"elementor-heading-title elementor-size-default\">\u201c\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e15\u0e49\u0e21\u0e2a\u0e01\u0e31\u0e14\u0e14\u0e49\u0e27\u0e22\u0e19\u0e49\u0e33\u0e02\u0e19\u0e32\u0e14\u0e43\u0e2b\u0e0d\u0e48\u201d (Extractor Tank)<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b3ab1a4 elementor-widget elementor-widget-text-editor\" data-id=\"b3ab1a4\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>\u0e40\u0e1b\u0e47\u0e19\u0e16\u0e31\u0e07\u0e15\u0e49\u0e21\u0e2a\u0e01\u0e31\u0e14\u0e2a\u0e41\u0e15\u0e19\u0e40\u0e25\u0e2a \u0e02\u0e19\u0e32\u0e14 1500\u0e25\u0e34\u0e15\u0e23 \u0e08\u0e33\u0e19\u0e27\u0e19 2 \u0e16\u0e31\u0e07 \u0e40\u0e1b\u0e47\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e01\u0e31\u0e14\u0e2a\u0e32\u0e23\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e08\u0e32\u0e01\u0e1e\u0e37\u0e0a\u0e2a\u0e21\u0e38\u0e19\u0e44\u0e1e\u0e23\u0e42\u0e14\u0e22\u0e43\u0e0a\u0e49\u0e19\u0e49\u0e33\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e17\u0e33\u0e25\u0e30\u0e25\u0e32\u0e22\u0e43\u0e0a\u0e49\u0e27\u0e34\u0e18\u0e35\u0e15\u0e49\u0e21\u0e41\u0e25\u0e30\u0e01\u0e27\u0e19\u0e14\u0e49\u0e27\u0e22\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19 \u0e42\u0e14\u0e22\u0e43\u0e2b\u0e49\u0e19\u0e49\u0e33\u0e23\u0e49\u0e2d\u0e19\u0e17\u0e33\u0e01\u0e32\u0e23\u0e0a\u0e30\u0e40\u0e2d\u0e32\u0e2a\u0e32\u0e23\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e2d\u0e2d\u0e01\u0e21\u0e32\u0e08\u0e32\u0e01\u0e2a\u0e21\u0e38\u0e19\u0e44\u0e1e\u0e23 \u0e15\u0e31\u0e27\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e43\u0e2b\u0e49\u0e40\u0e1b\u0e47\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e01\u0e31\u0e14\u0e41\u0e1a\u0e1a\u0e44\u0e2b\u0e25<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-082d02d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"082d02d\" data-element_type=\"section\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-cae6574\" data-id=\"cae6574\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4278370 elementor-widget elementor-widget-image\" data-id=\"4278370\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.napbiotec.io\/wp-content\/uploads\/2022\/06\/line-3.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-title=\"line 3\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MzE1NywidXJsIjoiaHR0cHM6XC9cL3d3dy5uYXBiaW90ZWMuY29tXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDIyXC8wNlwvbGluZS0zLmpwZyJ9\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"800\" height=\"721\" src=\"https:\/\/www.napbiotec.com\/wp-content\/uploads\/2022\/06\/line-3-1024x923.jpg\" class=\"elementor-animation-grow attachment-large size-large wp-image-3157\" alt=\"\" srcset=\"https:\/\/www.napbiotec.com\/wp-content\/uploads\/2022\/06\/line-3-1024x923.jpg 1024w, https:\/\/www.napbiotec.com\/wp-content\/uploads\/2022\/06\/line-3-600x541.jpg 600w, https:\/\/www.napbiotec.com\/wp-content\/uploads\/2022\/06\/line-3-300x270.jpg 300w, https:\/\/www.napbiotec.com\/wp-content\/uploads\/2022\/06\/line-3-768x692.jpg 768w, https:\/\/www.napbiotec.com\/wp-content\/uploads\/2022\/06\/line-3-13x12.jpg 13w, https:\/\/www.napbiotec.com\/wp-content\/uploads\/2022\/06\/line-3.jpg 1110w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-12e6893\" data-id=\"12e6893\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ea70d06 elementor-widget elementor-widget-heading\" data-id=\"ea70d06\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u201c\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e15\u0e49\u0e21\u0e2a\u0e01\u0e31\u0e14\u0e41\u0e1a\u0e1a\u0e2a\u0e39\u0e0d\u0e0d\u0e32\u0e01\u0e32\u0e28\u201d (Vacuum Extractor)<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0702bcf elementor-widget elementor-widget-text-editor\" data-id=\"0702bcf\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e01\u0e31\u0e14\u0e2a\u0e21\u0e38\u0e19\u0e44\u0e1e\u0e23 \u0e14\u0e49\u0e27\u0e22\u0e15\u0e31\u0e27\u0e17\u0e33\u0e25\u0e30\u0e25\u0e32\u0e22\u0e41\u0e2d\u0e25\u0e01\u0e2d\u0e2e\u0e2d\u0e25\u0e4c\u0e43\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e38\u0e0d\u0e0d\u0e32\u0e01\u0e32\u0e28 \u0e02\u0e19\u0e32\u0e14\u0e16\u0e31\u0e07 500 \u0e25\u0e34\u0e15\u0e23 \u0e0b\u0e36\u0e48\u0e07\u0e08\u0e30\u0e17\u0e33\u0e43\u0e2b\u0e49\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e02\u0e2d\u0e07\u0e2a\u0e32\u0e23\u0e2a\u0e01\u0e31\u0e14\u0e22\u0e31\u0e07\u0e04\u0e07\u0e2d\u0e22\u0e39\u0e48 \u0e44\u0e21\u0e48\u0e2a\u0e39\u0e0d\u0e2a\u0e25\u0e32\u0e22\u0e44\u0e1b\u0e01\u0e31\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19\u0e41\u0e25\u0e30\u0e22\u0e31\u0e07\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e40\u0e01\u0e47\u0e1a\u0e40\u0e2d\u0e17\u0e18\u0e32\u0e19\u0e2d\u0e25\u0e01\u0e25\u0e31\u0e1a\u0e44\u0e14\u0e49\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e19\u0e33\u0e21\u0e32\u0e43\u0e0a\u0e49\u0e2a\u0e01\u0e31\u0e14\u0e43\u0e2b\u0e21\u0e48\u0e44\u0e14\u0e49\u0e2d\u0e35\u0e01\u0e2b\u0e25\u0e32\u0e22\u0e04\u0e23\u0e31\u0e49\u0e07<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-92cafb5 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"92cafb5\" data-element_type=\"section\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-966f4b1\" data-id=\"966f4b1\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8a61ab1 elementor-widget elementor-widget-image\" data-id=\"8a61ab1\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.napbiotec.io\/wp-content\/uploads\/2022\/06\/line-4.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-title=\"line 4\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MzE1OCwidXJsIjoiaHR0cHM6XC9cL3d3dy5uYXBiaW90ZWMuY29tXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDIyXC8wNlwvbGluZS00LmpwZyJ9\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"800\" height=\"721\" src=\"https:\/\/www.napbiotec.com\/wp-content\/uploads\/2022\/06\/line-4-1024x923.jpg\" class=\"elementor-animation-grow attachment-large size-large wp-image-3158\" alt=\"\" srcset=\"https:\/\/www.napbiotec.com\/wp-content\/uploads\/2022\/06\/line-4-1024x923.jpg 1024w, https:\/\/www.napbiotec.com\/wp-content\/uploads\/2022\/06\/line-4-600x541.jpg 600w, https:\/\/www.napbiotec.com\/wp-content\/uploads\/2022\/06\/line-4-300x270.jpg 300w, https:\/\/www.napbiotec.com\/wp-content\/uploads\/2022\/06\/line-4-768x692.jpg 768w, https:\/\/www.napbiotec.com\/wp-content\/uploads\/2022\/06\/line-4-13x12.jpg 13w, https:\/\/www.napbiotec.com\/wp-content\/uploads\/2022\/06\/line-4.jpg 1110w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-5cb1728\" data-id=\"5cb1728\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-52bbb32 elementor-widget elementor-widget-heading\" data-id=\"52bbb32\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u201c\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e01\u0e31\u0e14\u0e14\u0e49\u0e27\u0e22\u0e04\u0e25\u0e37\u0e48\u0e19\u0e2d\u0e31\u0e25\u0e15\u0e23\u0e32\u0e42\u0e0b\u0e19\u0e34\u0e04\u201d (Ultrasonic Extractor)<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-19d05cc elementor-widget elementor-widget-text-editor\" data-id=\"19d05cc\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>\u0e40\u0e1b\u0e47\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e01\u0e31\u0e14\u0e14\u0e49\u0e27\u0e22\u0e04\u0e25\u0e37\u0e48\u0e19\u0e04\u0e27\u0e32\u0e21\u0e16\u0e35\u0e48\u0e2a\u0e39\u0e07\u0e2d\u0e31\u0e25\u0e15\u0e23\u0e32\u0e42\u0e0b\u0e19\u0e34\u0e04 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e44\u0e1b\u0e01\u0e23\u0e30\u0e17\u0e1a\u0e01\u0e31\u0e1a\u0e1c\u0e19\u0e31\u0e07\u0e40\u0e0b\u0e25\u0e2a\u0e4c\u0e02\u0e2d\u0e07\u0e2a\u0e21\u0e38\u0e19\u0e44\u0e1e\u0e23\u0e43\u0e2b\u0e49\u0e41\u0e15\u0e01\u0e2d\u0e2d\u0e01\u0e0b\u0e36\u0e48\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e17\u0e04\u0e19\u0e34\u0e04\u0e17\u0e35\u0e48\u0e44\u0e21\u0e48\u0e43\u0e0a\u0e49\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19\u0e0a\u0e48\u0e27\u0e22\u0e43\u0e2b\u0e49\u0e2a\u0e32\u0e23\u0e2a\u0e01\u0e31\u0e14\u0e22\u0e31\u0e07\u0e04\u0e07\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e41\u0e25\u0e30\u0e44\u0e21\u0e48\u0e2a\u0e39\u0e0d\u0e40\u0e2a\u0e35\u0e22\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e02\u0e2d\u0e07\u0e2a\u0e21\u0e38\u0e19\u0e44\u0e1e\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e30\u0e2b\u0e22\u0e31\u0e14\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-de22457 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"de22457\" data-element_type=\"section\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-a653868\" data-id=\"a653868\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cd5b036 elementor-widget elementor-widget-image\" data-id=\"cd5b036\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.napbiotec.io\/wp-content\/uploads\/2022\/06\/line-5.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-title=\"line 5\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MzE1OSwidXJsIjoiaHR0cHM6XC9cL3d3dy5uYXBiaW90ZWMuY29tXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDIyXC8wNlwvbGluZS01LmpwZyJ9\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"721\" src=\"https:\/\/www.napbiotec.com\/wp-content\/uploads\/2022\/06\/line-5-1024x923.jpg\" class=\"elementor-animation-grow attachment-large size-large wp-image-3159\" alt=\"\" srcset=\"https:\/\/www.napbiotec.com\/wp-content\/uploads\/2022\/06\/line-5-1024x923.jpg 1024w, https:\/\/www.napbiotec.com\/wp-content\/uploads\/2022\/06\/line-5-600x541.jpg 600w, https:\/\/www.napbiotec.com\/wp-content\/uploads\/2022\/06\/line-5-300x270.jpg 300w, https:\/\/www.napbiotec.com\/wp-content\/uploads\/2022\/06\/line-5-768x692.jpg 768w, https:\/\/www.napbiotec.com\/wp-content\/uploads\/2022\/06\/line-5-13x12.jpg 13w, https:\/\/www.napbiotec.com\/wp-content\/uploads\/2022\/06\/line-5.jpg 1110w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-04796ad\" data-id=\"04796ad\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4c9da82 elementor-widget elementor-widget-heading\" data-id=\"4c9da82\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u201c\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e01\u0e31\u0e14\u0e14\u0e49\u0e27\u0e22\u0e01\u0e4a\u0e32\u0e0b\u0e04\u0e32\u0e23\u0e4c\u0e1a\u0e2d\u0e19\u0e44\u0e14\u0e2d\u0e2d\u0e01\u0e44\u0e0b\u0e14\u0e4c Co2\u201d (Supercritical Co2 EXtractor)<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c17fc49 elementor-widget elementor-widget-text-editor\" data-id=\"c17fc49\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>\u0e40\u0e1b\u0e47\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e01\u0e31\u0e14\u0e2a\u0e32\u0e23\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e08\u0e32\u0e01\u0e1e\u0e37\u0e0a\u0e2a\u0e21\u0e38\u0e19\u0e44\u0e1e\u0e23\u0e42\u0e14\u0e22\u0e43\u0e0a\u0e49\u0e01\u0e4a\u0e32\u0e0b carbon dioxide (CO2) \u0e17\u0e35\u0e48\u0e04\u0e27\u0e32\u0e21\u0e14\u0e31\u0e19\u0e21\u0e32\u0e01\u0e01\u0e27\u0e48\u0e32 300 \u0e40\u0e17\u0e48\u0e32\u0e02\u0e2d\u0e07\u0e0a\u0e31\u0e49\u0e19\u0e1a\u0e23\u0e23\u0e22\u0e32\u0e01\u0e32\u0e28 \u0e41\u0e25\u0e30 \u0e17\u0e35\u0e48\u0e2d\u0e38\u0e13\u0e2b\u0e20\u0e39\u0e21\u0e34\u0e40\u0e2b\u0e21\u0e32\u0e30\u0e2a\u0e21 \u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13 30 \u0e2d\u0e07\u0e28\u0e32\u0e40\u0e0b\u0e25\u0e40\u0e0b\u0e35\u0e22\u0e2a<\/p><p>\u0e0b\u0e36\u0e48\u0e07\u0e17\u0e33\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48\u0e04\u0e25\u0e49\u0e32\u0e22\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e2a\u0e01\u0e31\u0e14\u0e14\u0e49\u0e27\u0e22\u0e15\u0e31\u0e27\u0e17\u0e33\u0e25\u0e30\u0e25\u0e32\u0e22 \u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e2d\u0e38\u0e13\u0e2b\u0e20\u0e39\u0e21\u0e34\u0e17\u0e35\u0e48\u0e15\u0e48\u0e33\u0e19\u0e31\u0e49\u0e19\u0e08\u0e30\u0e17\u0e33\u0e43\u0e2b\u0e49\u0e2a\u0e32\u0e23\u0e2a\u0e33\u0e04\u0e31\u0e0d (Active Ingredients) \u0e22\u0e31\u0e07\u0e04\u0e07\u0e2d\u0e22\u0e39\u0e48\u0e41\u0e25\u0e30\u0e44\u0e21\u0e48\u0e16\u0e39\u0e01\u0e17\u0e33\u0e25\u0e32\u0e22\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e43\u0e01\u0e25\u0e49\u0e40\u0e04\u0e35\u0e22\u0e07\u0e01\u0e31\u0e1a\u0e2a\u0e32\u0e23\u0e17\u0e35\u0e48\u0e21\u0e35\u0e2d\u0e22\u0e39\u0e48\u0e43\u0e19\u0e18\u0e23\u0e23\u0e21\u0e0a\u0e32\u0e15\u0e34 \u0e40\u0e1e\u0e23\u0e32\u0e30\u0e40\u0e2b\u0e15\u0e38\u0e19\u0e35\u0e49\u0e08\u0e36\u0e07\u0e17\u0e33\u0e43\u0e2b\u0e49\u0e2a\u0e32\u0e23\u0e17\u0e35\u0e48\u0e2a\u0e01\u0e31\u0e14\u0e14\u0e49\u0e27\u0e22\u0e01\u0e23\u0e23\u0e21\u0e27\u0e34\u0e18\u0e35\u0e19\u0e35\u0e49\u0e22\u0e31\u0e07\u0e04\u0e07\u0e04\u0e38\u0e13\u0e2a\u0e21\u0e1a\u0e31\u0e15\u0e34\u0e02\u0e2d\u0e07\u0e1e\u0e37\u0e0a\u0e19\u0e31\u0e49\u0e19\u0e46 100% \u0e41\u0e25\u0e30\u0e1b\u0e23\u0e32\u0e28\u0e08\u0e32\u0e01\u0e2a\u0e32\u0e23\u0e1b\u0e19\u0e40\u0e1b\u0e37\u0e49\u0e2d\u0e19\u0e02\u0e2d\u0e07\u0e15\u0e31\u0e27\u0e17\u0e33\u0e25\u0e30\u0e25\u0e32\u0e22 (S olvent) \u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e01\u0e31\u0e14<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5dd28b8 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5dd28b8\" data-element_type=\"section\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-33abded\" data-id=\"33abded\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ee48b70 elementor-widget elementor-widget-image\" data-id=\"ee48b70\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.napbiotec.io\/wp-content\/uploads\/2022\/06\/line-6.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-title=\"line 6\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MzE2MCwidXJsIjoiaHR0cHM6XC9cL3d3dy5uYXBiaW90ZWMuY29tXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDIyXC8wNlwvbGluZS02LmpwZyJ9\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"721\" src=\"https:\/\/www.napbiotec.com\/wp-content\/uploads\/2022\/06\/line-6-1024x923.jpg\" class=\"elementor-animation-grow attachment-large size-large wp-image-3160\" alt=\"\" srcset=\"https:\/\/www.napbiotec.com\/wp-content\/uploads\/2022\/06\/line-6-1024x923.jpg 1024w, https:\/\/www.napbiotec.com\/wp-content\/uploads\/2022\/06\/line-6-600x541.jpg 600w, https:\/\/www.napbiotec.com\/wp-content\/uploads\/2022\/06\/line-6-300x270.jpg 300w, https:\/\/www.napbiotec.com\/wp-content\/uploads\/2022\/06\/line-6-768x692.jpg 768w, https:\/\/www.napbiotec.com\/wp-content\/uploads\/2022\/06\/line-6-13x12.jpg 13w, https:\/\/www.napbiotec.com\/wp-content\/uploads\/2022\/06\/line-6.jpg 1110w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-b7be64d\" data-id=\"b7be64d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-30dacae elementor-widget elementor-widget-heading\" data-id=\"30dacae\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u201c\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e01\u0e31\u0e14\u0e40\u0e22\u0e47\u0e19\u201d (Cold Oil Screw Press)<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-058a28a elementor-widget elementor-widget-text-editor\" data-id=\"058a28a\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e01\u0e31\u0e14\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e41\u0e1a\u0e1a\u0e40\u0e22\u0e47\u0e19\u0e14\u0e49\u0e27\u0e22\u0e40\u0e01\u0e25\u0e35\u0e22\u0e27\u0e1a\u0e35\u0e1a\u0e2d\u0e31\u0e14\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e01\u0e31\u0e14\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e2d\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e27\u0e31\u0e15\u0e16\u0e38\u0e14\u0e34\u0e1a\u0e0b\u0e36\u0e48\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e01\u0e31\u0e14\u0e40\u0e22\u0e47\u0e19\u0e40\u0e2b\u0e21\u0e32\u0e30\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e2a\u0e01\u0e31\u0e14\u0e27\u0e31\u0e15\u0e16\u0e38\u0e14\u0e34\u0e1a\u0e17\u0e35\u0e48\u0e21\u0e35\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e40\u0e1b\u0e47\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e43\u0e19\u0e1b\u0e23\u0e34\u0e21\u0e32\u0e13\u0e21\u0e32\u0e01 \u0e42\u0e14\u0e22\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e01\u0e31\u0e14\u0e08\u0e30\u0e17\u0e33\u0e07\u0e32\u0e19\u0e14\u0e49\u0e27\u0e22\u0e01\u0e32\u0e23\u0e1a\u0e35\u0e1a\u0e41\u0e25\u0e30\u0e01\u0e23\u0e2d\u0e07\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e2d\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e01\u0e32\u0e01 \u0e17\u0e33\u0e43\u0e2b\u0e49\u0e44\u0e14\u0e49\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e35\u0e48\u0e43\u0e2a\u0e0b\u0e36\u0e48\u0e07\u0e01\u0e32\u0e23\u0e2a\u0e01\u0e31\u0e14\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e41\u0e1a\u0e1a\u0e40\u0e22\u0e47\u0e19\u0e19\u0e35\u0e49\u0e43\u0e0a\u0e49\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e43\u0e19\u0e01\u0e23\u0e30\u0e1a\u0e27\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e01\u0e31\u0e14\u0e19\u0e49\u0e2d\u0e22\u0e41\u0e25\u0e30\u0e17\u0e33\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e2d\u0e38\u0e13\u0e2b\u0e20\u0e39\u0e21\u0e34\u0e15\u0e48\u0e33\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e23\u0e31\u0e01\u0e29\u0e32\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e2a\u0e35\u0e01\u0e25\u0e34\u0e48\u0e19\u0e41\u0e25\u0e30\u0e23\u0e2a\u0e0a\u0e32\u0e15\u0e34\u0e02\u0e2d\u0e07\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e44\u0e14\u0e49\u0e14\u0e35\u0e01\u0e27\u0e48\u0e32<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-47b32a2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"47b32a2\" data-element_type=\"section\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-33d52c6\" data-id=\"33d52c6\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c3fb896 elementor-widget elementor-widget-image\" data-id=\"c3fb896\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.napbiotec.io\/wp-content\/uploads\/2022\/06\/line-7.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-title=\"line 7\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MzE2MSwidXJsIjoiaHR0cHM6XC9cL3d3dy5uYXBiaW90ZWMuY29tXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDIyXC8wNlwvbGluZS03LmpwZyJ9\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"721\" src=\"https:\/\/www.napbiotec.com\/wp-content\/uploads\/2022\/06\/line-7-1024x923.jpg\" class=\"elementor-animation-grow attachment-large size-large wp-image-3161\" alt=\"\" srcset=\"https:\/\/www.napbiotec.com\/wp-content\/uploads\/2022\/06\/line-7-1024x923.jpg 1024w, https:\/\/www.napbiotec.com\/wp-content\/uploads\/2022\/06\/line-7-600x541.jpg 600w, https:\/\/www.napbiotec.com\/wp-content\/uploads\/2022\/06\/line-7-300x270.jpg 300w, https:\/\/www.napbiotec.com\/wp-content\/uploads\/2022\/06\/line-7-768x692.jpg 768w, https:\/\/www.napbiotec.com\/wp-content\/uploads\/2022\/06\/line-7-13x12.jpg 13w, https:\/\/www.napbiotec.com\/wp-content\/uploads\/2022\/06\/line-7.jpg 1110w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-a6c6a2a\" data-id=\"a6c6a2a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bbc4b41 elementor-widget elementor-widget-heading\" data-id=\"bbc4b41\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u201c\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e01\u0e31\u0e14\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e2b\u0e2d\u0e21\u0e23\u0e30\u0e40\u0e2b\u0e22\u0e14\u0e49\u0e27\u0e22\u0e44\u0e2d\u0e19\u0e49\u0e33\u201d \n(Steam Distillation)<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f327499 elementor-widget elementor-widget-text-editor\" data-id=\"f327499\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>\u0e16\u0e31\u0e07\u0e15\u0e49\u0e21\u0e2a\u0e01\u0e31\u0e14\u0e02\u0e19\u0e32\u0e14 500 \u0e25\u0e34\u0e15\u0e23 \u0e40\u0e1b\u0e47\u0e19\u0e27\u0e34\u0e18\u0e35\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e44\u0e2d\u0e19\u0e49\u0e33\u0e1c\u0e48\u0e32\u0e19\u0e27\u0e31\u0e15\u0e16\u0e38\u0e14\u0e34\u0e1a\u0e17\u0e35\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e2a\u0e01\u0e31\u0e14\u0e43\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e1b\u0e34\u0e14\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e44\u0e2d\u0e19\u0e49\u0e33\u0e1e\u0e32\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e2d\u0e2d\u0e01\u0e21\u0e32\u0e41\u0e25\u0e30\u0e1c\u0e48\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e04\u0e27\u0e1a\u0e41\u0e19\u0e48\u0e19\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e44\u0e14\u0e49\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e2b\u0e2d\u0e21\u0e23\u0e30\u0e40\u0e2b\u0e22<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>\u0e01\u0e32\u0e23\u0e08\u0e30\u0e21\u0e35\u0e2a\u0e32\u0e23\u0e2a\u0e01\u0e31\u0e14\u0e2a\u0e21\u0e38\u0e19\u0e44\u0e1e\u0e23\u0e17\u0e35\u0e48\u0e21\u0e35\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e \u0e01\u0e47\u0e15\u0e49\u0e2d\u0e07\u0e21\u0e35\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e01\u0e31\u0e14\u0e2a\u0e21\u0e38\u0e19\u0e44\u0e1e\u0e23\u0e17\u0e35\u0e48\u0e21\u0e35\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e40\u0e0a\u0e48\u0e19\u0e01\u0e31\u0e19 \u0e41\u0e25\u0e49\u0e27\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e01\u0e31\u0e14\u0e2a\u0e21\u0e38\u0e19\u0e44\u0e1e\u0e23\u0e02\u0e2d\u0e07 NAP \u0e08\u0e30\u0e21\u0e35\u0e2b\u0e19\u0e49\u0e32\u0e15\u0e32\u0e40\u0e1b\u0e47\u0e19\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e44\u0e23 \u0e40\u0e23\u0e32\u0e44\u0e1b\u0e14\u0e39\u0e01\u0e31\u0e19\u0e40\u0e25\u0e22 \u201c\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e15\u0e49\u0e21\u0e2a\u0e01\u0e31\u0e14\u0e14\u0e49\u0e27\u0e22\u0e19\u0e49\u0e33\u0e02\u0e19\u0e32\u0e14\u0e43\u0e2b\u0e0d\u0e48\u201d (Extractor Tank) \u0e40\u0e1b\u0e47\u0e19\u0e16\u0e31\u0e07\u0e15\u0e49\u0e21\u0e2a\u0e01\u0e31\u0e14\u0e2a\u0e41\u0e15\u0e19\u0e40\u0e25\u0e2a \u0e02\u0e19\u0e32\u0e14 1500\u0e25\u0e34\u0e15\u0e23 \u0e08\u0e33\u0e19\u0e27\u0e19 2 \u0e16\u0e31\u0e07 \u0e40\u0e1b\u0e47\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e01\u0e31\u0e14\u0e2a\u0e32\u0e23\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e08\u0e32\u0e01\u0e1e\u0e37\u0e0a\u0e2a\u0e21\u0e38\u0e19\u0e44\u0e1e\u0e23\u0e42\u0e14\u0e22\u0e43\u0e0a\u0e49\u0e19\u0e49\u0e33\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e17\u0e33\u0e25\u0e30\u0e25\u0e32\u0e22\u0e43\u0e0a\u0e49\u0e27\u0e34\u0e18\u0e35\u0e15\u0e49\u0e21\u0e41\u0e25\u0e30\u0e01\u0e27\u0e19\u0e14\u0e49\u0e27\u0e22\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19 \u0e42\u0e14\u0e22\u0e43\u0e2b\u0e49\u0e19\u0e49\u0e33\u0e23\u0e49\u0e2d\u0e19\u0e17\u0e33\u0e01\u0e32\u0e23\u0e0a\u0e30\u0e40\u0e2d\u0e32\u0e2a\u0e32\u0e23\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e2d\u0e2d\u0e01\u0e21\u0e32\u0e08\u0e32\u0e01\u0e2a\u0e21\u0e38\u0e19\u0e44\u0e1e\u0e23 \u0e15\u0e31\u0e27\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e43\u0e2b\u0e49\u0e40\u0e1b\u0e47\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e01\u0e31\u0e14\u0e41\u0e1a\u0e1a\u0e44\u0e2b\u0e25 \u201c\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e15\u0e49\u0e21\u0e2a\u0e01\u0e31\u0e14\u0e41\u0e1a\u0e1a\u0e2a\u0e39\u0e0d\u0e0d\u0e32\u0e01\u0e32\u0e28\u201d (Vacuum Extractor) \u0e43\u0e0a\u0e49\u0e43\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e01\u0e31\u0e14\u0e2a\u0e21\u0e38\u0e19\u0e44\u0e1e\u0e23 \u0e14\u0e49\u0e27\u0e22\u0e15\u0e31\u0e27\u0e17\u0e33\u0e25\u0e30\u0e25\u0e32\u0e22\u0e41\u0e2d\u0e25\u0e01\u0e2d\u0e2e\u0e2d\u0e25\u0e4c\u0e43\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e38\u0e0d\u0e0d\u0e32\u0e01\u0e32\u0e28 \u0e02\u0e19\u0e32\u0e14\u0e16\u0e31\u0e07 500 \u0e25\u0e34\u0e15\u0e23 \u0e0b\u0e36\u0e48\u0e07\u0e08\u0e30\u0e17\u0e33\u0e43\u0e2b\u0e49\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e02\u0e2d\u0e07\u0e2a\u0e32\u0e23\u0e2a\u0e01\u0e31\u0e14\u0e22\u0e31\u0e07\u0e04\u0e07\u0e2d\u0e22\u0e39\u0e48 \u0e44\u0e21\u0e48\u0e2a\u0e39\u0e0d\u0e2a\u0e25\u0e32\u0e22\u0e44\u0e1b\u0e01\u0e31\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19\u0e41\u0e25\u0e30\u0e22\u0e31\u0e07\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e40\u0e01\u0e47\u0e1a\u0e40\u0e2d\u0e17\u0e18\u0e32\u0e19\u0e2d\u0e25\u0e01\u0e25\u0e31\u0e1a\u0e44\u0e14\u0e49\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e19\u0e33\u0e21\u0e32\u0e43\u0e0a\u0e49\u0e2a\u0e01\u0e31\u0e14\u0e43\u0e2b\u0e21\u0e48\u0e44\u0e14\u0e49\u0e2d\u0e35\u0e01\u0e2b\u0e25\u0e32\u0e22\u0e04\u0e23\u0e31\u0e49\u0e07 \u201c\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e01\u0e31\u0e14\u0e14\u0e49\u0e27\u0e22\u0e04\u0e25\u0e37\u0e48\u0e19\u0e2d\u0e31\u0e25\u0e15\u0e23\u0e32\u0e42\u0e0b\u0e19\u0e34\u0e04\u201d (Ultrasonic Extractor) \u0e40\u0e1b\u0e47\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e01\u0e31\u0e14\u0e14\u0e49\u0e27\u0e22\u0e04\u0e25\u0e37\u0e48\u0e19\u0e04\u0e27\u0e32\u0e21\u0e16\u0e35\u0e48\u0e2a\u0e39\u0e07\u0e2d\u0e31\u0e25\u0e15\u0e23\u0e32\u0e42\u0e0b\u0e19\u0e34\u0e04 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e44\u0e1b\u0e01\u0e23\u0e30\u0e17\u0e1a\u0e01\u0e31\u0e1a\u0e1c\u0e19\u0e31\u0e07\u0e40\u0e0b\u0e25\u0e2a\u0e4c\u0e02\u0e2d\u0e07\u0e2a\u0e21\u0e38\u0e19\u0e44\u0e1e\u0e23\u0e43\u0e2b\u0e49\u0e41\u0e15\u0e01\u0e2d\u0e2d\u0e01\u0e0b\u0e36\u0e48\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e17\u0e04\u0e19\u0e34\u0e04\u0e17\u0e35\u0e48\u0e44\u0e21\u0e48\u0e43\u0e0a\u0e49\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19\u0e0a\u0e48\u0e27\u0e22\u0e43\u0e2b\u0e49\u0e2a\u0e32\u0e23\u0e2a\u0e01\u0e31\u0e14\u0e22\u0e31\u0e07\u0e04\u0e07\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e41\u0e25\u0e30\u0e44\u0e21\u0e48\u0e2a\u0e39\u0e0d\u0e40\u0e2a\u0e35\u0e22\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e02\u0e2d\u0e07\u0e2a\u0e21\u0e38\u0e19\u0e44\u0e1e\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e30\u0e2b\u0e22\u0e31\u0e14\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19 \u201c\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e01\u0e31\u0e14\u0e14\u0e49\u0e27\u0e22\u0e01\u0e4a\u0e32\u0e0b\u0e04\u0e32\u0e23\u0e4c\u0e1a\u0e2d\u0e19\u0e44\u0e14\u0e2d\u0e2d\u0e01\u0e44\u0e0b\u0e14\u0e4c Co2\u201d (Supercritical Co2 EXtractor) \u0e40\u0e1b\u0e47\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e01\u0e31\u0e14\u0e2a\u0e32\u0e23\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e08\u0e32\u0e01\u0e1e\u0e37\u0e0a\u0e2a\u0e21\u0e38\u0e19\u0e44\u0e1e\u0e23\u0e42\u0e14\u0e22\u0e43\u0e0a\u0e49\u0e01\u0e4a\u0e32\u0e0b carbon dioxide (CO2) \u0e17\u0e35\u0e48\u0e04\u0e27\u0e32\u0e21\u0e14\u0e31\u0e19\u0e21\u0e32\u0e01\u0e01\u0e27\u0e48\u0e32 300 \u0e40\u0e17\u0e48\u0e32\u0e02\u0e2d\u0e07\u0e0a\u0e31\u0e49\u0e19\u0e1a\u0e23\u0e23\u0e22\u0e32\u0e01\u0e32\u0e28 \u0e41\u0e25\u0e30 \u0e17\u0e35\u0e48\u0e2d\u0e38\u0e13\u0e2b\u0e20\u0e39\u0e21\u0e34\u0e40\u0e2b\u0e21\u0e32\u0e30\u0e2a\u0e21 \u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13 30 \u0e2d\u0e07\u0e28\u0e32\u0e40\u0e0b\u0e25\u0e40\u0e0b\u0e35\u0e22\u0e2a \u0e0b\u0e36\u0e48\u0e07\u0e17\u0e33\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48\u0e04\u0e25\u0e49\u0e32\u0e22\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e2a\u0e01\u0e31\u0e14\u0e14\u0e49\u0e27\u0e22\u0e15\u0e31\u0e27\u0e17\u0e33\u0e25\u0e30\u0e25\u0e32\u0e22 \u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e2d\u0e38\u0e13\u0e2b\u0e20\u0e39\u0e21\u0e34\u0e17\u0e35\u0e48\u0e15\u0e48\u0e33\u0e19\u0e31\u0e49\u0e19\u0e08\u0e30\u0e17\u0e33\u0e43\u0e2b\u0e49\u0e2a\u0e32\u0e23\u0e2a\u0e33\u0e04\u0e31\u0e0d (Active Ingredients) \u0e22\u0e31\u0e07\u0e04\u0e07\u0e2d\u0e22\u0e39\u0e48\u0e41\u0e25\u0e30\u0e44\u0e21\u0e48\u0e16\u0e39\u0e01\u0e17\u0e33\u0e25\u0e32\u0e22\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e43\u0e01\u0e25\u0e49\u0e40\u0e04\u0e35\u0e22\u0e07\u0e01\u0e31\u0e1a\u0e2a\u0e32\u0e23\u0e17\u0e35\u0e48\u0e21\u0e35\u0e2d\u0e22\u0e39\u0e48\u0e43\u0e19\u0e18\u0e23\u0e23\u0e21\u0e0a\u0e32\u0e15\u0e34 [&hellip;]<\/p>","protected":false},"author":1,"featured_media":3154,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[72],"tags":[88,74,81,73,83,79,215,216,76],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e01\u0e31\u0e14\u0e2a\u0e38\u0e14\u0e25\u0e49\u0e33 \u0e17\u0e35\u0e48\u0e17\u0e33\u0e43\u0e2b\u0e49 NAP \u0e44\u0e21\u0e48\u0e40\u0e2b\u0e21\u0e37\u0e2d\u0e19\u0e43\u0e04\u0e23 - NAP Biotec Co., Ltd.<\/title>\n<meta name=\"description\" content=\"\u0e01\u0e32\u0e23\u0e08\u0e30\u0e21\u0e35\u0e2a\u0e32\u0e23\u0e2a\u0e01\u0e31\u0e14\u0e2a\u0e21\u0e38\u0e19\u0e44\u0e1e\u0e23\u0e17\u0e35\u0e48\u0e21\u0e35\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e \u0e01\u0e47\u0e15\u0e49\u0e2d\u0e07\u0e21\u0e35\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e01\u0e31\u0e14\u0e2a\u0e21\u0e38\u0e19\u0e44\u0e1e\u0e23\u0e17\u0e35\u0e48\u0e21\u0e35\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e40\u0e0a\u0e48\u0e19\u0e01\u0e31\u0e19 \u0e41\u0e25\u0e49\u0e27\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e01\u0e31\u0e14\u0e2a\u0e21\u0e38\u0e19\u0e44\u0e1e\u0e23\u0e02\u0e2d\u0e07 NAP \u0e08\u0e30\u0e21\u0e35\u0e2b\u0e19\u0e49\u0e32\u0e15\u0e32\u0e40\u0e1b\u0e47\u0e19\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e44\u0e23\u0e44\u0e1b\u0e14\u0e39\u0e01\u0e31\u0e19\u0e40\u0e25\u0e22\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.napbiotec.io\/machine-extract-for-nap\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e01\u0e31\u0e14\u0e2a\u0e38\u0e14\u0e25\u0e49\u0e33 \u0e17\u0e35\u0e48\u0e17\u0e33\u0e43\u0e2b\u0e49 NAP \u0e44\u0e21\u0e48\u0e40\u0e2b\u0e21\u0e37\u0e2d\u0e19\u0e43\u0e04\u0e23 - NAP Biotec Co., Ltd.\" \/>\n<meta property=\"og:description\" content=\"\u0e01\u0e32\u0e23\u0e08\u0e30\u0e21\u0e35\u0e2a\u0e32\u0e23\u0e2a\u0e01\u0e31\u0e14\u0e2a\u0e21\u0e38\u0e19\u0e44\u0e1e\u0e23\u0e17\u0e35\u0e48\u0e21\u0e35\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e \u0e01\u0e47\u0e15\u0e49\u0e2d\u0e07\u0e21\u0e35\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e01\u0e31\u0e14\u0e2a\u0e21\u0e38\u0e19\u0e44\u0e1e\u0e23\u0e17\u0e35\u0e48\u0e21\u0e35\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e40\u0e0a\u0e48\u0e19\u0e01\u0e31\u0e19 \u0e41\u0e25\u0e49\u0e27\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e01\u0e31\u0e14\u0e2a\u0e21\u0e38\u0e19\u0e44\u0e1e\u0e23\u0e02\u0e2d\u0e07 NAP \u0e08\u0e30\u0e21\u0e35\u0e2b\u0e19\u0e49\u0e32\u0e15\u0e32\u0e40\u0e1b\u0e47\u0e19\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e44\u0e23\u0e44\u0e1b\u0e14\u0e39\u0e01\u0e31\u0e19\u0e40\u0e25\u0e22\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.napbiotec.io\/machine-extract-for-nap\/\" \/>\n<meta property=\"og:site_name\" content=\"NAP Biotec Co., Ltd.\" \/>\n<meta property=\"article:published_time\" content=\"2022-06-25T18:11:40+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-06-25T18:12:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.napbiotec.io\/wp-content\/uploads\/2022\/06\/\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e01\u0e31\u0e14\u0e2a\u0e38\u0e14\u0e25\u0e49\u0e33-\u0e17\u0e35\u0e48\u0e17\u0e33\u0e43\u0e2b\u0e49-Nap-\u0e44\u0e21\u0e48\u0e40\u0e2b\u0e21\u0e37\u0e2d\u0e19\u0e43\u0e04\u0e23-web.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"628\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.napbiotec.io\/machine-extract-for-nap\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.napbiotec.io\/machine-extract-for-nap\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\/\/www.napbiotec.io\/en\/#\/schema\/person\/a3649044e4001f425b91e29f78da002e\"},\"headline\":\"\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e01\u0e31\u0e14\u0e2a\u0e38\u0e14\u0e25\u0e49\u0e33 \u0e17\u0e35\u0e48\u0e17\u0e33\u0e43\u0e2b\u0e49 NAP \u0e44\u0e21\u0e48\u0e40\u0e2b\u0e21\u0e37\u0e2d\u0e19\u0e43\u0e04\u0e23\",\"datePublished\":\"2022-06-25T18:11:40+00:00\",\"dateModified\":\"2022-06-25T18:12:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.napbiotec.io\/machine-extract-for-nap\/\"},\"wordCount\":25,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.napbiotec.io\/en\/#organization\"},\"keywords\":[\"Extract\",\"\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\",\"\u0e19\u0e32\u0e42\u0e19\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\",\"\u0e2a\u0e01\u0e31\u0e14\u0e08\u0e32\u0e01\u0e18\u0e23\u0e23\u0e21\u0e0a\u0e32\u0e15\u0e34\",\"\u0e2a\u0e21\u0e38\u0e19\u0e44\u0e1e\u0e23\",\"\u0e2a\u0e32\u0e23\u0e2a\u0e01\u0e31\u0e14\",\"\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\",\"\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e01\u0e31\u0e14\",\"\u0e41\u0e19\u0e47\u0e1e\u0e44\u0e1a\u0e42\u0e2d\u0e40\u0e17\u0e04\"],\"articleSection\":[\"\u0e04\u0e25\u0e31\u0e07\u0e1a\u0e17\u0e04\u0e27\u0e32\u0e21\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.napbiotec.io\/machine-extract-for-nap\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.napbiotec.io\/machine-extract-for-nap\/\",\"url\":\"https:\/\/www.napbiotec.io\/machine-extract-for-nap\/\",\"name\":\"\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e01\u0e31\u0e14\u0e2a\u0e38\u0e14\u0e25\u0e49\u0e33 \u0e17\u0e35\u0e48\u0e17\u0e33\u0e43\u0e2b\u0e49 NAP \u0e44\u0e21\u0e48\u0e40\u0e2b\u0e21\u0e37\u0e2d\u0e19\u0e43\u0e04\u0e23 - NAP Biotec Co., Ltd.\",\"isPartOf\":{\"@id\":\"https:\/\/www.napbiotec.io\/en\/#website\"},\"datePublished\":\"2022-06-25T18:11:40+00:00\",\"dateModified\":\"2022-06-25T18:12:18+00:00\",\"description\":\"\u0e01\u0e32\u0e23\u0e08\u0e30\u0e21\u0e35\u0e2a\u0e32\u0e23\u0e2a\u0e01\u0e31\u0e14\u0e2a\u0e21\u0e38\u0e19\u0e44\u0e1e\u0e23\u0e17\u0e35\u0e48\u0e21\u0e35\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e \u0e01\u0e47\u0e15\u0e49\u0e2d\u0e07\u0e21\u0e35\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e01\u0e31\u0e14\u0e2a\u0e21\u0e38\u0e19\u0e44\u0e1e\u0e23\u0e17\u0e35\u0e48\u0e21\u0e35\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e40\u0e0a\u0e48\u0e19\u0e01\u0e31\u0e19 \u0e41\u0e25\u0e49\u0e27\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e01\u0e31\u0e14\u0e2a\u0e21\u0e38\u0e19\u0e44\u0e1e\u0e23\u0e02\u0e2d\u0e07 NAP \u0e08\u0e30\u0e21\u0e35\u0e2b\u0e19\u0e49\u0e32\u0e15\u0e32\u0e40\u0e1b\u0e47\u0e19\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e44\u0e23\u0e44\u0e1b\u0e14\u0e39\u0e01\u0e31\u0e19\u0e40\u0e25\u0e22\",\"breadcrumb\":{\"@id\":\"https:\/\/www.napbiotec.io\/machine-extract-for-nap\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.napbiotec.io\/machine-extract-for-nap\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.napbiotec.io\/machine-extract-for-nap\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.napbiotec.io\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e01\u0e31\u0e14\u0e2a\u0e38\u0e14\u0e25\u0e49\u0e33 \u0e17\u0e35\u0e48\u0e17\u0e33\u0e43\u0e2b\u0e49 NAP \u0e44\u0e21\u0e48\u0e40\u0e2b\u0e21\u0e37\u0e2d\u0e19\u0e43\u0e04\u0e23\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.napbiotec.io\/en\/#website\",\"url\":\"https:\/\/www.napbiotec.io\/en\/\",\"name\":\"NAP Biotec Co., Ltd.\",\"description\":\"\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e1c\u0e39\u0e49\u0e1c\u0e25\u0e34\u0e15\u0e41\u0e25\u0e30\u0e1c\u0e39\u0e49\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e32\u0e23\u0e2a\u0e01\u0e31\u0e14\u0e2a\u0e21\u0e38\u0e19\u0e44\u0e1e\u0e23\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e1e\u0e23\u0e35\u0e40\u0e21\u0e35\u0e48\u0e22\u0e21\u0e20\u0e32\u0e22\u0e43\u0e15\u0e49\u0e41\u0e1a\u0e23\u0e19\u0e14\u0e4c \u0e19\u0e32\u0e41\u0e17\u0e23\u0e47\u0e01\u0e0b\u0e4c \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e21\u0e32\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e17\u0e33\u0e43\u0e2b\u0e49\u0e44\u0e14\u0e49\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e43\u0e2b\u0e21\u0e48 \u0e46\",\"publisher\":{\"@id\":\"https:\/\/www.napbiotec.io\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.napbiotec.io\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.napbiotec.io\/en\/#organization\",\"name\":\"Napbiotec\",\"url\":\"https:\/\/www.napbiotec.io\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.napbiotec.io\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.napbiotec.io\/wp-content\/uploads\/2022\/03\/naplogo300.png\",\"contentUrl\":\"https:\/\/www.napbiotec.io\/wp-content\/uploads\/2022\/03\/naplogo300.png\",\"width\":300,\"height\":300,\"caption\":\"Napbiotec\"},\"image\":{\"@id\":\"https:\/\/www.napbiotec.io\/en\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.napbiotec.io\/en\/#\/schema\/person\/a3649044e4001f425b91e29f78da002e\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.napbiotec.io\/en\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/68f947cc86b2040210064d6bd42b3e18?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/68f947cc86b2040210064d6bd42b3e18?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"https:\/\/wp.devops.napbiotec.io\"],\"url\":\"https:\/\/www.napbiotec.com\/en\/author\/admin\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e01\u0e31\u0e14\u0e2a\u0e38\u0e14\u0e25\u0e49\u0e33 \u0e17\u0e35\u0e48\u0e17\u0e33\u0e43\u0e2b\u0e49 NAP \u0e44\u0e21\u0e48\u0e40\u0e2b\u0e21\u0e37\u0e2d\u0e19\u0e43\u0e04\u0e23 - NAP Biotec Co., Ltd.","description":"\u0e01\u0e32\u0e23\u0e08\u0e30\u0e21\u0e35\u0e2a\u0e32\u0e23\u0e2a\u0e01\u0e31\u0e14\u0e2a\u0e21\u0e38\u0e19\u0e44\u0e1e\u0e23\u0e17\u0e35\u0e48\u0e21\u0e35\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e \u0e01\u0e47\u0e15\u0e49\u0e2d\u0e07\u0e21\u0e35\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e01\u0e31\u0e14\u0e2a\u0e21\u0e38\u0e19\u0e44\u0e1e\u0e23\u0e17\u0e35\u0e48\u0e21\u0e35\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e40\u0e0a\u0e48\u0e19\u0e01\u0e31\u0e19 \u0e41\u0e25\u0e49\u0e27\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e01\u0e31\u0e14\u0e2a\u0e21\u0e38\u0e19\u0e44\u0e1e\u0e23\u0e02\u0e2d\u0e07 NAP \u0e08\u0e30\u0e21\u0e35\u0e2b\u0e19\u0e49\u0e32\u0e15\u0e32\u0e40\u0e1b\u0e47\u0e19\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e44\u0e23\u0e44\u0e1b\u0e14\u0e39\u0e01\u0e31\u0e19\u0e40\u0e25\u0e22","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.napbiotec.io\/machine-extract-for-nap\/","og_locale":"en_US","og_type":"article","og_title":"\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e01\u0e31\u0e14\u0e2a\u0e38\u0e14\u0e25\u0e49\u0e33 \u0e17\u0e35\u0e48\u0e17\u0e33\u0e43\u0e2b\u0e49 NAP \u0e44\u0e21\u0e48\u0e40\u0e2b\u0e21\u0e37\u0e2d\u0e19\u0e43\u0e04\u0e23 - NAP Biotec Co., Ltd.","og_description":"\u0e01\u0e32\u0e23\u0e08\u0e30\u0e21\u0e35\u0e2a\u0e32\u0e23\u0e2a\u0e01\u0e31\u0e14\u0e2a\u0e21\u0e38\u0e19\u0e44\u0e1e\u0e23\u0e17\u0e35\u0e48\u0e21\u0e35\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e \u0e01\u0e47\u0e15\u0e49\u0e2d\u0e07\u0e21\u0e35\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e01\u0e31\u0e14\u0e2a\u0e21\u0e38\u0e19\u0e44\u0e1e\u0e23\u0e17\u0e35\u0e48\u0e21\u0e35\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e40\u0e0a\u0e48\u0e19\u0e01\u0e31\u0e19 \u0e41\u0e25\u0e49\u0e27\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e01\u0e31\u0e14\u0e2a\u0e21\u0e38\u0e19\u0e44\u0e1e\u0e23\u0e02\u0e2d\u0e07 NAP \u0e08\u0e30\u0e21\u0e35\u0e2b\u0e19\u0e49\u0e32\u0e15\u0e32\u0e40\u0e1b\u0e47\u0e19\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e44\u0e23\u0e44\u0e1b\u0e14\u0e39\u0e01\u0e31\u0e19\u0e40\u0e25\u0e22","og_url":"https:\/\/www.napbiotec.io\/machine-extract-for-nap\/","og_site_name":"NAP Biotec Co., Ltd.","article_published_time":"2022-06-25T18:11:40+00:00","article_modified_time":"2022-06-25T18:12:18+00:00","og_image":[{"width":1200,"height":628,"url":"https:\/\/www.napbiotec.io\/wp-content\/uploads\/2022\/06\/\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e01\u0e31\u0e14\u0e2a\u0e38\u0e14\u0e25\u0e49\u0e33-\u0e17\u0e35\u0e48\u0e17\u0e33\u0e43\u0e2b\u0e49-Nap-\u0e44\u0e21\u0e48\u0e40\u0e2b\u0e21\u0e37\u0e2d\u0e19\u0e43\u0e04\u0e23-web.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Written by":"admin","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.napbiotec.io\/machine-extract-for-nap\/#article","isPartOf":{"@id":"https:\/\/www.napbiotec.io\/machine-extract-for-nap\/"},"author":{"name":"admin","@id":"https:\/\/www.napbiotec.io\/en\/#\/schema\/person\/a3649044e4001f425b91e29f78da002e"},"headline":"\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e01\u0e31\u0e14\u0e2a\u0e38\u0e14\u0e25\u0e49\u0e33 \u0e17\u0e35\u0e48\u0e17\u0e33\u0e43\u0e2b\u0e49 NAP \u0e44\u0e21\u0e48\u0e40\u0e2b\u0e21\u0e37\u0e2d\u0e19\u0e43\u0e04\u0e23","datePublished":"2022-06-25T18:11:40+00:00","dateModified":"2022-06-25T18:12:18+00:00","mainEntityOfPage":{"@id":"https:\/\/www.napbiotec.io\/machine-extract-for-nap\/"},"wordCount":25,"commentCount":0,"publisher":{"@id":"https:\/\/www.napbiotec.io\/en\/#organization"},"keywords":["Extract","\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21","\u0e19\u0e32\u0e42\u0e19\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35","\u0e2a\u0e01\u0e31\u0e14\u0e08\u0e32\u0e01\u0e18\u0e23\u0e23\u0e21\u0e0a\u0e32\u0e15\u0e34","\u0e2a\u0e21\u0e38\u0e19\u0e44\u0e1e\u0e23","\u0e2a\u0e32\u0e23\u0e2a\u0e01\u0e31\u0e14","\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07","\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e01\u0e31\u0e14","\u0e41\u0e19\u0e47\u0e1e\u0e44\u0e1a\u0e42\u0e2d\u0e40\u0e17\u0e04"],"articleSection":["\u0e04\u0e25\u0e31\u0e07\u0e1a\u0e17\u0e04\u0e27\u0e32\u0e21"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.napbiotec.io\/machine-extract-for-nap\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.napbiotec.io\/machine-extract-for-nap\/","url":"https:\/\/www.napbiotec.io\/machine-extract-for-nap\/","name":"\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e01\u0e31\u0e14\u0e2a\u0e38\u0e14\u0e25\u0e49\u0e33 \u0e17\u0e35\u0e48\u0e17\u0e33\u0e43\u0e2b\u0e49 NAP \u0e44\u0e21\u0e48\u0e40\u0e2b\u0e21\u0e37\u0e2d\u0e19\u0e43\u0e04\u0e23 - NAP Biotec Co., Ltd.","isPartOf":{"@id":"https:\/\/www.napbiotec.io\/en\/#website"},"datePublished":"2022-06-25T18:11:40+00:00","dateModified":"2022-06-25T18:12:18+00:00","description":"\u0e01\u0e32\u0e23\u0e08\u0e30\u0e21\u0e35\u0e2a\u0e32\u0e23\u0e2a\u0e01\u0e31\u0e14\u0e2a\u0e21\u0e38\u0e19\u0e44\u0e1e\u0e23\u0e17\u0e35\u0e48\u0e21\u0e35\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e \u0e01\u0e47\u0e15\u0e49\u0e2d\u0e07\u0e21\u0e35\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e01\u0e31\u0e14\u0e2a\u0e21\u0e38\u0e19\u0e44\u0e1e\u0e23\u0e17\u0e35\u0e48\u0e21\u0e35\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e40\u0e0a\u0e48\u0e19\u0e01\u0e31\u0e19 \u0e41\u0e25\u0e49\u0e27\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e01\u0e31\u0e14\u0e2a\u0e21\u0e38\u0e19\u0e44\u0e1e\u0e23\u0e02\u0e2d\u0e07 NAP \u0e08\u0e30\u0e21\u0e35\u0e2b\u0e19\u0e49\u0e32\u0e15\u0e32\u0e40\u0e1b\u0e47\u0e19\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e44\u0e23\u0e44\u0e1b\u0e14\u0e39\u0e01\u0e31\u0e19\u0e40\u0e25\u0e22","breadcrumb":{"@id":"https:\/\/www.napbiotec.io\/machine-extract-for-nap\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.napbiotec.io\/machine-extract-for-nap\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.napbiotec.io\/machine-extract-for-nap\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.napbiotec.io\/en\/"},{"@type":"ListItem","position":2,"name":"\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e01\u0e31\u0e14\u0e2a\u0e38\u0e14\u0e25\u0e49\u0e33 \u0e17\u0e35\u0e48\u0e17\u0e33\u0e43\u0e2b\u0e49 NAP \u0e44\u0e21\u0e48\u0e40\u0e2b\u0e21\u0e37\u0e2d\u0e19\u0e43\u0e04\u0e23"}]},{"@type":"WebSite","@id":"https:\/\/www.napbiotec.io\/en\/#website","url":"https:\/\/www.napbiotec.io\/en\/","name":"NAP Biotec Co., Ltd.","description":"\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e1c\u0e39\u0e49\u0e1c\u0e25\u0e34\u0e15\u0e41\u0e25\u0e30\u0e1c\u0e39\u0e49\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e32\u0e23\u0e2a\u0e01\u0e31\u0e14\u0e2a\u0e21\u0e38\u0e19\u0e44\u0e1e\u0e23\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e1e\u0e23\u0e35\u0e40\u0e21\u0e35\u0e48\u0e22\u0e21\u0e20\u0e32\u0e22\u0e43\u0e15\u0e49\u0e41\u0e1a\u0e23\u0e19\u0e14\u0e4c \u0e19\u0e32\u0e41\u0e17\u0e23\u0e47\u0e01\u0e0b\u0e4c \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e21\u0e32\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e17\u0e33\u0e43\u0e2b\u0e49\u0e44\u0e14\u0e49\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e43\u0e2b\u0e21\u0e48 \u0e46","publisher":{"@id":"https:\/\/www.napbiotec.io\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.napbiotec.io\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.napbiotec.io\/en\/#organization","name":"Napbiotec","url":"https:\/\/www.napbiotec.io\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.napbiotec.io\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.napbiotec.io\/wp-content\/uploads\/2022\/03\/naplogo300.png","contentUrl":"https:\/\/www.napbiotec.io\/wp-content\/uploads\/2022\/03\/naplogo300.png","width":300,"height":300,"caption":"Napbiotec"},"image":{"@id":"https:\/\/www.napbiotec.io\/en\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.napbiotec.io\/en\/#\/schema\/person\/a3649044e4001f425b91e29f78da002e","name":"admin","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.napbiotec.io\/en\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/68f947cc86b2040210064d6bd42b3e18?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/68f947cc86b2040210064d6bd42b3e18?s=96&d=mm&r=g","caption":"admin"},"sameAs":["https:\/\/wp.devops.napbiotec.io"],"url":"https:\/\/www.napbiotec.com\/en\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/www.napbiotec.com\/en\/wp-json\/wp\/v2\/posts\/3153"}],"collection":[{"href":"https:\/\/www.napbiotec.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.napbiotec.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.napbiotec.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.napbiotec.com\/en\/wp-json\/wp\/v2\/comments?post=3153"}],"version-history":[{"count":7,"href":"https:\/\/www.napbiotec.com\/en\/wp-json\/wp\/v2\/posts\/3153\/revisions"}],"predecessor-version":[{"id":3167,"href":"https:\/\/www.napbiotec.com\/en\/wp-json\/wp\/v2\/posts\/3153\/revisions\/3167"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.napbiotec.com\/en\/wp-json\/wp\/v2\/media\/3154"}],"wp:attachment":[{"href":"https:\/\/www.napbiotec.com\/en\/wp-json\/wp\/v2\/media?parent=3153"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.napbiotec.com\/en\/wp-json\/wp\/v2\/categories?post=3153"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.napbiotec.com\/en\/wp-json\/wp\/v2\/tags?post=3153"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}